{"id":76887,"date":"2025-08-26T01:00:58","date_gmt":"2025-08-25T23:00:58","guid":{"rendered":"https:\/\/www.vernicirioverde.it\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/"},"modified":"2025-08-26T01:00:58","modified_gmt":"2025-08-25T23:00:58","slug":"colortecnica-di-angelon-luciana-ve-1635","status":"publish","type":"pv-rioverde","link":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/","title":{"rendered":"COLORTECNICA DI ANGELON LUCIANA"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><div id=\"__langwrap\"><\/div>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"id":"1635","nome-negozio":"COLORTECNICA DI ANGELON LUCIANA","cap":"30100","telefono":"0415010098","email":"colortecnica.venezia@gmail.com","sito-web":"","latitude":"45.4838901","longitude":"12.2639438","indirizzo":"Via Eugenio Pertini, 20","facebook":"","instagram":"","immagine-negozio":"","indicazioni":"https:\/\/www.google.com\/maps\/dir\/?api=1&destination=45.4838901,12.2639438"},"tipologia-store":[1530],"comune":[866],"provincia":[2966],"nazione":[423],"class_list":["post-76887","pv-rioverde","type-pv-rioverde","status-publish","hentry","tipologia-store-store","comune-venezia","provincia-ve","nazione-italia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COLORTECNICA DI ANGELON LUCIANA - Vernici Rio Verde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLORTECNICA DI ANGELON LUCIANA - Vernici Rio Verde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernici Rio Verde\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/pv-rioverde\\\/colortecnica-di-angelon-luciana-ve-1635\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/pv-rioverde\\\/colortecnica-di-angelon-luciana-ve-1635\\\/\",\"name\":\"COLORTECNICA DI ANGELON LUCIANA - Vernici Rio Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/#website\"},\"datePublished\":\"2025-08-25T23:00:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/pv-rioverde\\\/colortecnica-di-angelon-luciana-ve-1635\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/pv-rioverde\\\/colortecnica-di-angelon-luciana-ve-1635\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/pv-rioverde\\\/colortecnica-di-angelon-luciana-ve-1635\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stores\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/pv-rioverde\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COLORTECNICA DI ANGELON LUCIANA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/\",\"name\":\"Vernici Rio Verde\",\"description\":\"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/#organization\",\"name\":\"Vernici Rio Verde\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"width\":350,\"height\":100,\"caption\":\"Vernici Rio Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLORTECNICA DI ANGELON LUCIANA - Vernici Rio Verde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/","og_locale":"en_US","og_type":"article","og_title":"COLORTECNICA DI ANGELON LUCIANA - Vernici Rio Verde","og_url":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/","og_site_name":"Vernici Rio Verde","og_image":[{"width":700,"height":200,"url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/","url":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/","name":"COLORTECNICA DI ANGELON LUCIANA - Vernici Rio Verde","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/en\/#website"},"datePublished":"2025-08-25T23:00:58+00:00","breadcrumb":{"@id":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/colortecnica-di-angelon-luciana-ve-1635\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernicirioverde.it\/en\/"},{"@type":"ListItem","position":2,"name":"Stores","item":"https:\/\/www.vernicirioverde.it\/en\/pv-rioverde\/"},{"@type":"ListItem","position":3,"name":"COLORTECNICA DI ANGELON LUCIANA"}]},{"@type":"WebSite","@id":"https:\/\/www.vernicirioverde.it\/en\/#website","url":"https:\/\/www.vernicirioverde.it\/en\/","name":"Vernici Rio Verde","description":"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech","publisher":{"@id":"https:\/\/www.vernicirioverde.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernicirioverde.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.vernicirioverde.it\/en\/#organization","name":"Vernici Rio Verde","url":"https:\/\/www.vernicirioverde.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vernicirioverde.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","width":350,"height":100,"caption":"Vernici Rio Verde"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/en\/#\/schema\/logo\/image\/"}}]}},"terms":{"nazione":[{"id":423,"slug":"italia","name":"ITALIA"}],"comune":[{"id":866,"slug":"venezia","name":"Venezia"}],"provincia":[{"id":2966,"slug":"ve","name":"VE"}],"tipologia-store":[{"id":1530,"slug":"store","name":"store"}]},"_links":{"self":[{"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/pv-rioverde\/76887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/pv-rioverde"}],"about":[{"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/types\/pv-rioverde"}],"wp:attachment":[{"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/media?parent=76887"}],"wp:term":[{"taxonomy":"tipologia-store","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/tipologia-store?post=76887"},{"taxonomy":"comune","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/comune?post=76887"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/provincia?post=76887"},{"taxonomy":"nazione","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/en\/wp-json\/wp\/v2\/nazione?post=76887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}