{"id":2019,"count":1,"description":"","link":"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/","name":"Sant'Agata Li Battiati","slug":"santagata-li-battiati","taxonomy":"comune","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sant&#039;Agata Li Battiati Archives - Vernici Rio Verde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sant&#039;Agata Li Battiati Archives - Vernici Rio Verde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernici Rio Verde\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/comune\\\/santagata-li-battiati\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/comune\\\/santagata-li-battiati\\\/\",\"name\":\"Sant'Agata Li Battiati Archives - Vernici Rio Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/comune\\\/santagata-li-battiati\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/comune\\\/santagata-li-battiati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sant'Agata Li Battiati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\",\"name\":\"Vernici Rio Verde\",\"description\":\"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#organization\",\"name\":\"Vernici Rio Verde\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"width\":350,\"height\":100,\"caption\":\"Vernici Rio Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sant'Agata Li Battiati Archives - Vernici Rio Verde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/","og_locale":"es_ES","og_type":"article","og_title":"Sant'Agata Li Battiati Archives - Vernici Rio Verde","og_url":"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/","og_site_name":"Vernici Rio Verde","og_image":[{"width":700,"height":200,"url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/","url":"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/","name":"Sant'Agata Li Battiati Archives - Vernici Rio Verde","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/#breadcrumb"},"inLanguage":"es-ES"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernicirioverde.it\/es\/comune\/santagata-li-battiati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernicirioverde.it\/es\/"},{"@type":"ListItem","position":2,"name":"Sant'Agata Li Battiati"}]},{"@type":"WebSite","@id":"https:\/\/www.vernicirioverde.it\/es\/#website","url":"https:\/\/www.vernicirioverde.it\/es\/","name":"Vernici Rio Verde","description":"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech","publisher":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernicirioverde.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.vernicirioverde.it\/es\/#organization","name":"Vernici Rio Verde","url":"https:\/\/www.vernicirioverde.it\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","width":350,"height":100,"caption":"Vernici Rio Verde"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/comune\/2019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/comune"}],"about":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/taxonomies\/comune"}],"wp:post_type":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/pv-rioverde?comune=2019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}