{"id":62412,"date":"2020-10-21T17:27:07","date_gmt":"2020-10-21T15:27:07","guid":{"rendered":"https:\/\/www.vernicirioverde.it\/piante-in-camera-da-letto\/"},"modified":"2024-01-10T17:27:15","modified_gmt":"2024-01-10T16:27:15","slug":"piante-in-camera-da-letto","status":"publish","type":"post","link":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/","title":{"rendered":"#COLORES; \u00bfLAS PLANTAS EN EL DORMITORIO SON MALAS PARA LA SALUD?"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><div id=\"__langwrap\"><p>Los colocamos delante de la ventana francesa, en el alf&eacute;izar, cerca del radiador y en las estanter&iacute;as. &iquest;Y en el dormitorio? &iquest;Las plantas en el dormitorio encajan o son malas? Se lo prometimos la &uacute;ltima vez, cuando investigamos cu&aacute;les son las mejores <a href=\"https:\/\/www.vernicirioverde.it\/piante-da-interno\/\">plantas de interior<\/a> para te&ntilde;ir de verde nuestro hogar: hoy tratamos de responder a la pregunta derivada, la relativa a la colocaci&oacute;n -s&iacute; o no- de plantas en el dormitorio;    El punto de partida no admite discusi&oacute;n: las plantas, est&eacute;n donde est&eacute;n, son coreogr&aacute;ficas y calientan el ambiente; <strong>Pero, &iquest;pueden las plantas en el dormitorio ser perjudiciales para la salud?<\/strong><\/p>\n<div class=\"indice\">\n<p>&Iacute;ndice<\/p>\n<ul>\n<li><a href=\"#01\">S&Igrave; ALLE PIANTE IN CAMERA DA LETTO, LO DICE LA NASA<\/a><\/li>\n<li><a href=\"#02\">PLANTAS RECOMENDADAS PARA EL DORMITORIO<\/a><\/li>\n<\/ul>\n<\/div>\n<h2 id=\"01\">S&Iacute; A LAS PLANTAS EN EL DORMITORIO, DICE LA NASA<\/h2>\n<figure id=\"attachment_13973\" aria-describedby=\"caption-attachment-13973\" style=\"width: 960px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/s-alle-piante-in-camera-da-letto-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-13973\" src=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/s-alle-piante-in-camera-da-letto-1.jpg\" alt=\"\" width=\"960\" height=\"650\"><\/a><figcaption id=\"caption-attachment-13973\" class=\"wp-caption-text\">S&iacute; a las plantas en el dormitorio<\/figcaption><\/figure>\n<p>Cuenta la leyenda que las plantas en la habitaci&oacute;n donde duermes pueden ser perjudiciales para la salud debido al di&oacute;xido de carbono que emiten por la noche. Esto es cierto, pero hay un pero: las plantas consumen ox&iacute;geno y producen di&oacute;xido de carbono por la noche, pero <strong>si pensamos en la cantidad de CO&#8322;<\/strong> <strong>que emiten algunas plantas en el dormitorio, &eacute;sta es muy peque&ntilde;a<\/strong>. De hecho, no es capaz de perjudicar la salud de quien duerme a su lado. As&iacute; lo demuestran numerosos estudios, as&iacute; como un reciente descubrimiento de la NASA. En efecto, la agencia gubernamental civil responsable del programa espacial estadounidense y de la investigaci&oacute;n aeroespacial llev&oacute; a cabo una investigaci&oacute;n sobre c&oacute;mo mejorar el aire en el interior de las estaciones espaciales. Seg&uacute;n este estudio, incluso el aire de nuestras casas contiene ciertos elementos nocivos (presentes en el hogar debido a la contaminaci&oacute;n atmosf&eacute;rica o a los detergentes utilizados para la limpieza de las superficies dom&eacute;sticas y para aromatizar las habitaciones) que pueden neutralizarse hasta en un 85% mediante la presencia de ciertos tipos de plantas.     <\/p>\n<?xml encoding=\"utf-8\" ?><div id=\"__langwrap\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"62358\" class=\"elementor elementor-62358 elementor-58700\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ebe302 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ebe302\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"jet_parallax_layout_list\":[],\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41fc5d1\" data-id=\"41fc5d1\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9ebdd4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ebdd4d\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"jet_parallax_layout_list\":[],\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5474658 elementor-hidden-mobile\" data-id=\"5474658\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78fe0a6\" data-id=\"78fe0a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4869069 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"4869069\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings='{\"_animation\":\"pulse\",\"_animation_delay\":500}' data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/elementor\/thumbs\/icona_punti_vendita-r43envw6vxmss68dz6ec5ugunm1rf5jgza2j4m7wo0.png\" title=\"icona_punti_vendita\" alt=\"icona_punti_vendita\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe36a3 elementor-widget elementor-widget-heading\" data-id=\"fbe36a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Talleres de pintura<br>y fabricantes de colores<br>m&aacute;s cerca de usted<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d0de41 elementor-widget elementor-widget-jet-button\" data-id=\"1d0de41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-button jet-elements\"><div class=\"jet-button__container\">\n\t<a class=\"jet-button__instance jet-button__instance--icon-left hover-effect-0\" href=\"https:\/\/www.vernicirioverde.it\/punti-vendita\/\">\n\t\t<div class=\"jet-button__plane jet-button__plane-normal\"><\/div>\n\t\t<div class=\"jet-button__plane jet-button__plane-hover\"><\/div>\n\t\t<div class=\"jet-button__state jet-button__state-normal\">\n\t\t\t<span class=\"jet-button__label\">BUSCA LA TIENDA<\/span>\t\t<\/div>\n\t\t<div class=\"jet-button__state jet-button__state-hover\">\n\t\t\t<span class=\"jet-button__label\">BUSCA LA TIENDA<\/span>\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\n<h2 id=\"02\">PLANTAS RECOMENDADAS PARA EL DORMITORIO<\/h2>\n<figure id=\"attachment_13978\" aria-describedby=\"caption-attachment-13978\" style=\"width: 960px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/ci-sono-piante-che-depurano-laria-1.jpg\"><img decoding=\"async\" class=\"size-full wp-image-13978\" src=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/ci-sono-piante-che-depurano-laria-1.jpg\" alt=\"\" width=\"960\" height=\"650\"><\/a><figcaption id=\"caption-attachment-13978\" class=\"wp-caption-text\">Hay plantas que purifican el aire<\/figcaption><\/figure>\n<p>Seg&uacute;n la NASA, los beneficios de tener plantas en el dormitorio superan con creces cualquier &ldquo;da&ntilde;o&rdquo;. De hecho, hay plantas con el poder de limpiar el aire, absorbiendo sustancias nocivas y liberando ox&iacute;geno. En la pr&aacute;ctica, son purificadores naturales del aire. Veamos juntos algunos ejemplos;   <\/p>\n<ul>\n<li>La <strong>Areca<\/strong>: es la primera que hay que mencionar entre las plantas adecuadas para colocar en el dormitorio. Filtra el benceno, el tricloroetileno y el formaldeh&iacute;do, sobre todo si se coloca cerca de muebles pintados. Tambi&eacute;n es ideal en caso de resfriados frecuentes, ya que libera suficiente humedad en el aire para ayudar a respirar.  <\/li>\n<li>El <strong>aloe vera<\/strong> tiene el poder de liberar ox&iacute;geno durante la noche y de absorber el benceno y el formaldeh&iacute;do. Es f&aacute;cil de cuidar y no requiere cuidados especiales. Cuidado, sin embargo, con perros y gatos porque esta planta es t&oacute;xica para ellos.  <\/li>\n<li>La <strong>hiedra<\/strong> elimina eficazmente el moho, el tricloroetileno, el formaldeh&iacute;do, el benceno y el mon&oacute;xido de carbono. La hiedra tambi&eacute;n es t&oacute;xica para perros y gatos: mejor colocarla en una estanter&iacute;a (tambi&eacute;n es ideal desde el punto de vista decorativo). <\/li>\n<li>Las <strong>gerberas<\/strong> eliminan el tricloroetileno, el benceno y el formaldeh&iacute;do. No son t&oacute;xicas para perros ni gatos, as&iacute; que dale luz verde a las gerberas aunque tengas un amigo peludo en casa. <\/li>\n<li>La <strong>sanseveria<\/strong> emite ox&iacute;geno durante toda la noche; filtra el formaldeh&iacute;do, el tricloroetileno y el benceno; tambi&eacute;n absorbe el electrosmog producido por tel&eacute;fonos m&oacute;viles y ordenadores; es f&aacute;cil de cultivar; sus hojas de color verde brillante son preciosas. Cuidado: las hojas son t&oacute;xicas para perros y gatos. <\/li>\n<\/ul>\n<p><strong>Es mejor evitar, sin embargo, las plantas demasiado perfumadas<\/strong>: podr&iacute;an perturbar el sue&ntilde;o, provocar migra&ntilde;a o n&aacute;useas al despertar. Como norma general, sin embargo, las plantas deben colocarse siempre cerca de la ventana o la puerta, dej&aacute;ndola al menos entreabierta para facilitar el intercambio de aire. <\/p>\n<p>Como suele ocurrir, la mejor opci&oacute;n se encuentra en alg&uacute;n punto intermedio: las plantas en el dormitorio son buenas para usted si est&aacute;n en una cantidad proporcionada al tama&ntilde;o de la habitaci&oacute;n. No podemos dejar de mencionar el poder relajante de las plantas. <strong>En primer lugar por el color -el verde favorece el descanso- y en segundo lugar porque el contacto -aunque sea m&iacute;nimo- con la naturaleza siempre mejora el estado de &aacute;nimo<\/strong>. <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los colocamos delante de la ventana francesa, en el alf&eacute;izar, cerca del radiador y en las estanter&iacute;as. &iquest;Y en el dormitorio? &iquest;Las plantas en el dormitorio encajan o son malas? Se lo prometimos la &uacute;ltima vez, cuando investigamos cu&aacute;les son las mejores plantas de interior para te&ntilde;ir de verde nuestro hogar: hoy tratamos de responder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1586],"tags":[],"class_list":["post-62412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colors-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfLas plantas en el dormitorio son malas para la salud?<\/title>\n<meta name=\"description\" content=\"Las plantas, dondequiera que est\u00e9n, son coreogr\u00e1ficas y calientan el ambiente; Pero, \u00bfpueden las plantas en el dormitorio ser perjudiciales para la salud?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfLas plantas en el dormitorio son malas para la salud?\" \/>\n<meta property=\"og:description\" content=\"Las plantas, dondequiera que est\u00e9n, son coreogr\u00e1ficas y calientan el ambiente; Pero, \u00bfpueden las plantas en el dormitorio ser perjudiciales para la salud?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernici Rio Verde\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T15:27:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-10T16:27:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/piante-in-camera-da-letto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Developer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Developer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/\"},\"author\":{\"name\":\"Developer\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/person\\\/de73a2284fadd95063f9533d52ab19c3\"},\"headline\":\"#COLORES; \u00bfLAS PLANTAS EN EL DORMITORIO SON MALAS PARA LA SALUD?\",\"datePublished\":\"2020-10-21T15:27:07+00:00\",\"dateModified\":\"2024-01-10T16:27:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/\"},\"wordCount\":791,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/piante-in-camera-da-letto.jpg\",\"articleSection\":[\"#colors\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/\",\"name\":\"\u00bfLas plantas en el dormitorio son malas para la salud?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/piante-in-camera-da-letto.jpg\",\"datePublished\":\"2020-10-21T15:27:07+00:00\",\"dateModified\":\"2024-01-10T16:27:15+00:00\",\"description\":\"Las plantas, dondequiera que est\u00e9n, son coreogr\u00e1ficas y calientan el ambiente; Pero, \u00bfpueden las plantas en el dormitorio ser perjudiciales para la salud?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/piante-in-camera-da-letto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/piante-in-camera-da-letto.jpg\",\"width\":960,\"height\":650,\"caption\":\"Piante in camera da letto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/piante-in-camera-da-letto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#COLORES; \u00bfLAS PLANTAS EN EL DORMITORIO SON MALAS PARA LA SALUD?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\",\"name\":\"Vernici Rio Verde\",\"description\":\"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#organization\",\"name\":\"Vernici Rio Verde\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"width\":350,\"height\":100,\"caption\":\"Vernici Rio Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/person\\\/de73a2284fadd95063f9533d52ab19c3\",\"name\":\"Developer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfe62df277ebb9a2ce202b8ec40bf05cf408476d8e13a64cdbcde6f5832a8cfb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfe62df277ebb9a2ce202b8ec40bf05cf408476d8e13a64cdbcde6f5832a8cfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cfe62df277ebb9a2ce202b8ec40bf05cf408476d8e13a64cdbcde6f5832a8cfb?s=96&d=mm&r=g\",\"caption\":\"Developer\"},\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/author\\\/developer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfLas plantas en el dormitorio son malas para la salud?","description":"Las plantas, dondequiera que est\u00e9n, son coreogr\u00e1ficas y calientan el ambiente; Pero, \u00bfpueden las plantas en el dormitorio ser perjudiciales para la salud?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfLas plantas en el dormitorio son malas para la salud?","og_description":"Las plantas, dondequiera que est\u00e9n, son coreogr\u00e1ficas y calientan el ambiente; Pero, \u00bfpueden las plantas en el dormitorio ser perjudiciales para la salud?","og_url":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/","og_site_name":"Vernici Rio Verde","article_published_time":"2020-10-21T15:27:07+00:00","article_modified_time":"2024-01-10T16:27:15+00:00","og_image":[{"width":960,"height":650,"url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/piante-in-camera-da-letto.jpg","type":"image\/jpeg"}],"author":"Developer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Developer","Tiempo de lectura":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/#article","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/"},"author":{"name":"Developer","@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/person\/de73a2284fadd95063f9533d52ab19c3"},"headline":"#COLORES; \u00bfLAS PLANTAS EN EL DORMITORIO SON MALAS PARA LA SALUD?","datePublished":"2020-10-21T15:27:07+00:00","dateModified":"2024-01-10T16:27:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/"},"wordCount":791,"publisher":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#organization"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/piante-in-camera-da-letto.jpg","articleSection":["#colors"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/","url":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/","name":"\u00bfLas plantas en el dormitorio son malas para la salud?","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/#primaryimage"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/piante-in-camera-da-letto.jpg","datePublished":"2020-10-21T15:27:07+00:00","dateModified":"2024-01-10T16:27:15+00:00","description":"Las plantas, dondequiera que est\u00e9n, son coreogr\u00e1ficas y calientan el ambiente; Pero, \u00bfpueden las plantas en el dormitorio ser perjudiciales para la salud?","breadcrumb":{"@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/#primaryimage","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/piante-in-camera-da-letto.jpg","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2019\/10\/piante-in-camera-da-letto.jpg","width":960,"height":650,"caption":"Piante in camera da letto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernicirioverde.it\/es\/piante-in-camera-da-letto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernicirioverde.it\/es\/"},{"@type":"ListItem","position":2,"name":"#COLORES; \u00bfLAS PLANTAS EN EL DORMITORIO SON MALAS PARA LA SALUD?"}]},{"@type":"WebSite","@id":"https:\/\/www.vernicirioverde.it\/es\/#website","url":"https:\/\/www.vernicirioverde.it\/es\/","name":"Vernici Rio Verde","description":"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech","publisher":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernicirioverde.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.vernicirioverde.it\/es\/#organization","name":"Vernici Rio Verde","url":"https:\/\/www.vernicirioverde.it\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","width":350,"height":100,"caption":"Vernici Rio Verde"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/person\/de73a2284fadd95063f9533d52ab19c3","name":"Developer","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/cfe62df277ebb9a2ce202b8ec40bf05cf408476d8e13a64cdbcde6f5832a8cfb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cfe62df277ebb9a2ce202b8ec40bf05cf408476d8e13a64cdbcde6f5832a8cfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfe62df277ebb9a2ce202b8ec40bf05cf408476d8e13a64cdbcde6f5832a8cfb?s=96&d=mm&r=g","caption":"Developer"},"url":"https:\/\/www.vernicirioverde.it\/es\/author\/developer\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/posts\/62412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/comments?post=62412"}],"version-history":[{"count":0,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/posts\/62412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/media\/62413"}],"wp:attachment":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/media?parent=62412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/categories?post=62412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/tags?post=62412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}