{"id":48783,"date":"2025-09-04T01:00:16","date_gmt":"2025-09-03T23:00:16","guid":{"rendered":"https:\/\/www.vernicirioverde.it\/pv-rioverde\/color-rigolio-kino-color-s-n-c-di-caldiroli-daniele-c-va-384\/"},"modified":"2025-09-04T01:00:16","modified_gmt":"2025-09-03T23:00:16","slug":"color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384","status":"publish","type":"pv-rioverde","link":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/","title":{"rendered":"COLOR. RIGOLIO &#8211; KINO COLOR S.N.C. DI CALDIROLI DANIELE &#038; C."},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><div id=\"__langwrap\"><\/div>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"id":"384","nome-negozio":"COLOR. RIGOLIO - KINO COLOR S.N.C. DI CALDIROLI DANIELE & C.","cap":"21057","telefono":"033131075","email":"colorificio@kinocolor.it","sito-web":"","latitude":"45.6178523","longitude":"8.8747097","indirizzo":"Corso Sempione, 108\/112","facebook":"","instagram":"","immagine-negozio":"","indicazioni":"https:\/\/www.google.com\/maps\/dir\/?api=1&destination=45.6178523,8.8747097"},"tipologia-store":[1530],"comune":[620],"provincia":[2983],"nazione":[423],"class_list":["post-48783","pv-rioverde","type-pv-rioverde","status-publish","hentry","tipologia-store-store","comune-olgiate-olona","provincia-va","nazione-italia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COLOR. RIGOLIO - KINO COLOR S.N.C. DI CALDIROLI DANIELE &amp; C. - Vernici Rio Verde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLOR. RIGOLIO - KINO COLOR S.N.C. DI CALDIROLI DANIELE &amp; C. - Vernici Rio Verde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernici Rio Verde\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/pv-rioverde\\\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/pv-rioverde\\\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\\\/\",\"name\":\"COLOR. RIGOLIO - KINO COLOR S.N.C. DI CALDIROLI DANIELE & C. - Vernici Rio Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#website\"},\"datePublished\":\"2025-09-03T23:00:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/pv-rioverde\\\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/pv-rioverde\\\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/pv-rioverde\\\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puntos de venta\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/pv-rioverde\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COLOR. RIGOLIO &#8211; KINO COLOR S.N.C. DI CALDIROLI DANIELE &#038; C.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\",\"name\":\"Vernici Rio Verde\",\"description\":\"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#organization\",\"name\":\"Vernici Rio Verde\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"width\":350,\"height\":100,\"caption\":\"Vernici Rio Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLOR. RIGOLIO - KINO COLOR S.N.C. DI CALDIROLI DANIELE & C. - Vernici Rio Verde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/","og_locale":"es_ES","og_type":"article","og_title":"COLOR. RIGOLIO - KINO COLOR S.N.C. DI CALDIROLI DANIELE & C. - Vernici Rio Verde","og_url":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/","og_site_name":"Vernici Rio Verde","og_image":[{"width":700,"height":200,"url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/","url":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/","name":"COLOR. RIGOLIO - KINO COLOR S.N.C. DI CALDIROLI DANIELE & C. - Vernici Rio Verde","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#website"},"datePublished":"2025-09-03T23:00:16+00:00","breadcrumb":{"@id":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/color-rigolio-kino-color-snc-di-caldiroli-daniele-c-va-384\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernicirioverde.it\/es\/"},{"@type":"ListItem","position":2,"name":"Puntos de venta","item":"https:\/\/www.vernicirioverde.it\/es\/pv-rioverde\/"},{"@type":"ListItem","position":3,"name":"COLOR. RIGOLIO &#8211; KINO COLOR S.N.C. DI CALDIROLI DANIELE &#038; C."}]},{"@type":"WebSite","@id":"https:\/\/www.vernicirioverde.it\/es\/#website","url":"https:\/\/www.vernicirioverde.it\/es\/","name":"Vernici Rio Verde","description":"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech","publisher":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernicirioverde.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.vernicirioverde.it\/es\/#organization","name":"Vernici Rio Verde","url":"https:\/\/www.vernicirioverde.it\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","width":350,"height":100,"caption":"Vernici Rio Verde"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/es\/#\/schema\/logo\/image\/"}}]}},"terms":{"nazione":[{"id":423,"slug":"italia","name":"ITALIA"}],"comune":[{"id":620,"slug":"olgiate-olona","name":"Olgiate Olona"}],"provincia":[{"id":2983,"slug":"va","name":"VA"}],"tipologia-store":[{"id":1530,"slug":"store","name":"store"}]},"_links":{"self":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/pv-rioverde\/48783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/pv-rioverde"}],"about":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/types\/pv-rioverde"}],"wp:attachment":[{"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/media?parent=48783"}],"wp:term":[{"taxonomy":"tipologia-store","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/tipologia-store?post=48783"},{"taxonomy":"comune","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/comune?post=48783"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/provincia?post=48783"},{"taxonomy":"nazione","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/es\/wp-json\/wp\/v2\/nazione?post=48783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}