{"id":48538,"date":"2025-08-25T01:00:55","date_gmt":"2025-08-24T23:00:55","guid":{"rendered":"https:\/\/www.vernicirioverde.it\/pv-rioverde\/hempel-alicante-alicante-1157\/"},"modified":"2025-08-25T01:00:55","modified_gmt":"2025-08-24T23:00:55","slug":"hempel-alicante-1157","status":"publish","type":"pv-rioverde","link":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/","title":{"rendered":"HEMPEL ALICANTE"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><div id=\"__langwrap\"><\/div>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"id":"1157","nome-negozio":"HEMPEL ALICANTE","cap":"03007","telefono":"0034965120701","email":"carmenllorenshempel@gmail.com","sito-web":"","latitude":"38.3398466","longitude":"-0.4979893","indirizzo":"C\/ Perez Medina, 42","facebook":"","instagram":"","immagine-negozio":"","indicazioni":"https:\/\/www.google.com\/maps\/dir\/?api=1&destination=38.3398466,-0.4979893"},"tipologia-store":[1530],"comune":[1128],"provincia":[],"nazione":[424],"class_list":["post-48538","pv-rioverde","type-pv-rioverde","status-publish","hentry","tipologia-store-store","comune-alicante","nazione-espana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HEMPEL ALICANTE - Vernici Rio Verde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HEMPEL ALICANTE - Vernici Rio Verde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernici Rio Verde\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/pv-rioverde\\\/hempel-alicante-1157\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/pv-rioverde\\\/hempel-alicante-1157\\\/\",\"name\":\"HEMPEL ALICANTE - Vernici Rio Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/#website\"},\"datePublished\":\"2025-08-24T23:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/pv-rioverde\\\/hempel-alicante-1157\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/pv-rioverde\\\/hempel-alicante-1157\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/pv-rioverde\\\/hempel-alicante-1157\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Points de vente\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/pv-rioverde\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HEMPEL ALICANTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/\",\"name\":\"Vernici Rio Verde\",\"description\":\"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/#organization\",\"name\":\"Vernici Rio Verde\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"width\":350,\"height\":100,\"caption\":\"Vernici Rio Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HEMPEL ALICANTE - Vernici Rio Verde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/","og_locale":"fr_FR","og_type":"article","og_title":"HEMPEL ALICANTE - Vernici Rio Verde","og_url":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/","og_site_name":"Vernici Rio Verde","og_image":[{"width":700,"height":200,"url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/","url":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/","name":"HEMPEL ALICANTE - Vernici Rio Verde","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/fr\/#website"},"datePublished":"2025-08-24T23:00:55+00:00","breadcrumb":{"@id":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/hempel-alicante-1157\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernicirioverde.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Points de vente","item":"https:\/\/www.vernicirioverde.it\/fr\/pv-rioverde\/"},{"@type":"ListItem","position":3,"name":"HEMPEL ALICANTE"}]},{"@type":"WebSite","@id":"https:\/\/www.vernicirioverde.it\/fr\/#website","url":"https:\/\/www.vernicirioverde.it\/fr\/","name":"Vernici Rio Verde","description":"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech","publisher":{"@id":"https:\/\/www.vernicirioverde.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernicirioverde.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vernicirioverde.it\/fr\/#organization","name":"Vernici Rio Verde","url":"https:\/\/www.vernicirioverde.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vernicirioverde.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","width":350,"height":100,"caption":"Vernici Rio Verde"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/fr\/#\/schema\/logo\/image\/"}}]}},"terms":{"nazione":[{"id":424,"slug":"espana","name":"ESPA\u00d1A"}],"comune":[{"id":1128,"slug":"alicante","name":"ALICANTE"}],"provincia":[],"tipologia-store":[{"id":1530,"slug":"store","name":"store"}]},"_links":{"self":[{"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/pv-rioverde\/48538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/pv-rioverde"}],"about":[{"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/types\/pv-rioverde"}],"wp:attachment":[{"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/media?parent=48538"}],"wp:term":[{"taxonomy":"tipologia-store","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/tipologia-store?post=48538"},{"taxonomy":"comune","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/comune?post=48538"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/provincia?post=48538"},{"taxonomy":"nazione","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/fr\/wp-json\/wp\/v2\/nazione?post=48538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}