{"id":48590,"date":"2025-08-26T01:00:30","date_gmt":"2025-08-25T23:00:30","guid":{"rendered":"https:\/\/www.vernicirioverde.it\/pv-rioverde\/a-todo-color-badajoz-1394\/"},"modified":"2025-08-26T01:00:30","modified_gmt":"2025-08-25T23:00:30","slug":"a-todo-color-1394","status":"publish","type":"pv-rioverde","link":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/","title":{"rendered":"A TODO COLOR"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><div id=\"__langwrap\"><\/div>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"id":"1394","nome-negozio":"A TODO COLOR","cap":"06340","telefono":"0034645570593","email":"esmeraldandjorge@hotmail.com","sito-web":"","latitude":"38.1664265","longitude":"-6.6511018","indirizzo":"C\/ Libertad, 48","facebook":"","instagram":"","immagine-negozio":"","indicazioni":"https:\/\/www.google.com\/maps\/dir\/?api=1&destination=38.1664265,-6.65110179999999"},"tipologia-store":[1530],"comune":[1361],"provincia":[],"nazione":[424],"class_list":["post-48590","pv-rioverde","type-pv-rioverde","status-publish","hentry","tipologia-store-store","comune-fregenal-de-la-sierra","nazione-espana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A TODO COLOR - Vernici Rio Verde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A TODO COLOR - Vernici Rio Verde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernici Rio Verde\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/a-todo-color-1394\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/a-todo-color-1394\\\/\",\"name\":\"A TODO COLOR - Vernici Rio Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#website\"},\"datePublished\":\"2025-08-25T23:00:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/a-todo-color-1394\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/a-todo-color-1394\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/a-todo-color-1394\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Punkty sprzeda\u017cy\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A TODO COLOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/\",\"name\":\"Vernici Rio Verde\",\"description\":\"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#organization\",\"name\":\"Vernici Rio Verde\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"width\":350,\"height\":100,\"caption\":\"Vernici Rio Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A TODO COLOR - Vernici Rio Verde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/","og_locale":"pl_PL","og_type":"article","og_title":"A TODO COLOR - Vernici Rio Verde","og_url":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/","og_site_name":"Vernici Rio Verde","og_image":[{"width":700,"height":200,"url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/","url":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/","name":"A TODO COLOR - Vernici Rio Verde","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/#website"},"datePublished":"2025-08-25T23:00:30+00:00","breadcrumb":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/a-todo-color-1394\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernicirioverde.it\/pl\/"},{"@type":"ListItem","position":2,"name":"Punkty sprzeda\u017cy","item":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/"},{"@type":"ListItem","position":3,"name":"A TODO COLOR"}]},{"@type":"WebSite","@id":"https:\/\/www.vernicirioverde.it\/pl\/#website","url":"https:\/\/www.vernicirioverde.it\/pl\/","name":"Vernici Rio Verde","description":"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech","publisher":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernicirioverde.it\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.vernicirioverde.it\/pl\/#organization","name":"Vernici Rio Verde","url":"https:\/\/www.vernicirioverde.it\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.vernicirioverde.it\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","width":350,"height":100,"caption":"Vernici Rio Verde"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/#\/schema\/logo\/image\/"}}]}},"terms":{"nazione":[{"id":424,"slug":"espana","name":"ESPA\u00d1A"}],"comune":[{"id":1361,"slug":"fregenal-de-la-sierra","name":"FREGENAL DE LA SIERRA"}],"provincia":[],"tipologia-store":[{"id":1530,"slug":"store","name":"store"}]},"_links":{"self":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/pv-rioverde\/48590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/pv-rioverde"}],"about":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/types\/pv-rioverde"}],"wp:attachment":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/media?parent=48590"}],"wp:term":[{"taxonomy":"tipologia-store","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/tipologia-store?post=48590"},{"taxonomy":"comune","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/comune?post=48590"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/provincia?post=48590"},{"taxonomy":"nazione","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/nazione?post=48590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}