{"id":49450,"date":"2025-08-26T01:00:05","date_gmt":"2025-08-25T23:00:05","guid":{"rendered":"https:\/\/www.vernicirioverde.it\/pv-rioverde\/guidi-ferramenta-s-r-l-mo-1225\/"},"modified":"2025-08-26T01:00:05","modified_gmt":"2025-08-25T23:00:05","slug":"guidi-ferramenta-srl-mo-1225","status":"publish","type":"pv-rioverde","link":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/","title":{"rendered":"GUIDI FERRAMENTA S.R.L."},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><div id=\"__langwrap\"><\/div>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"id":"1225","nome-negozio":"GUIDI FERRAMENTA S.R.L.","cap":"41056","telefono":"059730213","email":"amministrazione@guidiferramenta.it","sito-web":"","latitude":"44.49102","longitude":"11.04371","indirizzo":"Via Claudia, 2273","facebook":"","instagram":"","immagine-negozio":"","indicazioni":"https:\/\/www.google.com\/maps\/dir\/?api=1&destination=44.49102,11.04371"},"tipologia-store":[1530],"comune":[688],"provincia":[3036],"nazione":[423],"class_list":["post-49450","pv-rioverde","type-pv-rioverde","status-publish","hentry","tipologia-store-store","comune-savignano-sul-panaro","provincia-mo","nazione-italia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GUIDI FERRAMENTA S.R.L. - Vernici Rio Verde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GUIDI FERRAMENTA S.R.L. - Vernici Rio Verde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernici Rio Verde\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/guidi-ferramenta-srl-mo-1225\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/guidi-ferramenta-srl-mo-1225\\\/\",\"name\":\"GUIDI FERRAMENTA S.R.L. - Vernici Rio Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#website\"},\"datePublished\":\"2025-08-25T23:00:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/guidi-ferramenta-srl-mo-1225\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/guidi-ferramenta-srl-mo-1225\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/guidi-ferramenta-srl-mo-1225\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Punkty sprzeda\u017cy\",\"item\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/pv-rioverde\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GUIDI FERRAMENTA S.R.L.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/\",\"name\":\"Vernici Rio Verde\",\"description\":\"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#organization\",\"name\":\"Vernici Rio Verde\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"contentUrl\":\"https:\\\/\\\/www.vernicirioverde.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo_RioVerde.png\",\"width\":350,\"height\":100,\"caption\":\"Vernici Rio Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernicirioverde.it\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GUIDI FERRAMENTA S.R.L. - Vernici Rio Verde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/","og_locale":"pl_PL","og_type":"article","og_title":"GUIDI FERRAMENTA S.R.L. - Vernici Rio Verde","og_url":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/","og_site_name":"Vernici Rio Verde","og_image":[{"width":700,"height":200,"url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde_x2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/","url":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/","name":"GUIDI FERRAMENTA S.R.L. - Vernici Rio Verde","isPartOf":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/#website"},"datePublished":"2025-08-25T23:00:05+00:00","breadcrumb":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/guidi-ferramenta-srl-mo-1225\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernicirioverde.it\/pl\/"},{"@type":"ListItem","position":2,"name":"Punkty sprzeda\u017cy","item":"https:\/\/www.vernicirioverde.it\/pl\/pv-rioverde\/"},{"@type":"ListItem","position":3,"name":"GUIDI FERRAMENTA S.R.L."}]},{"@type":"WebSite","@id":"https:\/\/www.vernicirioverde.it\/pl\/#website","url":"https:\/\/www.vernicirioverde.it\/pl\/","name":"Vernici Rio Verde","description":"La vernice per legno pensata per la protezione e la decorazione. Scegli Vintage Prestige e i tantissimi prodotti della gamma hi-tech","publisher":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernicirioverde.it\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.vernicirioverde.it\/pl\/#organization","name":"Vernici Rio Verde","url":"https:\/\/www.vernicirioverde.it\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.vernicirioverde.it\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","contentUrl":"https:\/\/www.vernicirioverde.it\/wp-content\/uploads\/2021\/07\/Logo_RioVerde.png","width":350,"height":100,"caption":"Vernici Rio Verde"},"image":{"@id":"https:\/\/www.vernicirioverde.it\/pl\/#\/schema\/logo\/image\/"}}]}},"terms":{"nazione":[{"id":423,"slug":"italia","name":"ITALIA"}],"comune":[{"id":688,"slug":"savignano-sul-panaro","name":"Savignano sul Panaro"}],"provincia":[{"id":3036,"slug":"mo","name":"MO"}],"tipologia-store":[{"id":1530,"slug":"store","name":"store"}]},"_links":{"self":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/pv-rioverde\/49450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/pv-rioverde"}],"about":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/types\/pv-rioverde"}],"wp:attachment":[{"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/media?parent=49450"}],"wp:term":[{"taxonomy":"tipologia-store","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/tipologia-store?post=49450"},{"taxonomy":"comune","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/comune?post=49450"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/provincia?post=49450"},{"taxonomy":"nazione","embeddable":true,"href":"https:\/\/www.vernicirioverde.it\/pl\/wp-json\/wp\/v2\/nazione?post=49450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}